{"id":4083,"date":"2017-10-26T11:45:29","date_gmt":"2017-10-26T11:45:29","guid":{"rendered":"https:\/\/kitakigazauberfloete.ch\/?p=4083"},"modified":"2023-08-15T11:58:58","modified_gmt":"2023-08-15T11:58:58","slug":"geburtstagfeier-im-wald","status":"publish","type":"post","link":"https:\/\/kitakigazauberfloete.ch\/en\/geburtstagfeier-im-wald\/","title":{"rendered":"Birthday Party in the Forest"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"4083\" class=\"elementor elementor-4083\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ada7676 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ada7676\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-664cf15\" data-id=\"664cf15\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13c43434 elementor-widget elementor-widget-text-editor\" data-id=\"13c43434\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Free movement and games of skill<br \/>After the exciting exploration of the forest with lots of exercise and great joy of discovery, we celebrated a children's birthday party. Of course, the candles and the fine little cakes could not be missing.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-956b037\" data-id=\"956b037\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c58f74f elementor-widget elementor-widget-image\" data-id=\"c58f74f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"574\" src=\"https:\/\/kitakigazauberfloete.ch\/wp-content\/uploads\/2019\/12\/Oktober-2017-2.png\" class=\"attachment-large size-large wp-image-3998\" alt=\"\" srcset=\"https:\/\/kitakigazauberfloete.ch\/wp-content\/uploads\/2019\/12\/Oktober-2017-2.png 614w, https:\/\/kitakigazauberfloete.ch\/wp-content\/uploads\/2019\/12\/Oktober-2017-2-300x287.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Freie Bewegung und GeschicklichkeitsspieleNach der spannenden Erkundung des Waldes mit viel Bewegung und gro\u00dfer Entdeckerfreude feierten wir einen Kindergeburtstag. Nat\u00fcrlich durften die Kerzen und die feinen kleinen Kuchen nicht fehlen.<\/p>","protected":false},"author":9,"featured_media":4819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","_crdt_document":"","inline_featured_image":false,"footnotes":""},"categories":[25],"tags":[],"class_list":["post-4083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-25"],"_links":{"self":[{"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/posts\/4083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/comments?post=4083"}],"version-history":[{"count":4,"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/posts\/4083\/revisions"}],"predecessor-version":[{"id":6678,"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/posts\/4083\/revisions\/6678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/media\/4819"}],"wp:attachment":[{"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/media?parent=4083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/categories?post=4083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kitakigazauberfloete.ch\/en\/wp-json\/wp\/v2\/tags?post=4083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}